{"id":242376,"date":"2023-12-07T10:21:09","date_gmt":"2023-12-07T09:21:09","guid":{"rendered":"https:\/\/schaeffner-neu.freischwimmer.de.com\/index.php\/2023\/12\/07\/hello-world\/"},"modified":"2025-03-27T17:10:53","modified_gmt":"2025-03-27T16:10:53","slug":"hello-world","status":"publish","type":"post","link":"https:\/\/schaeffner-neu.freischwimmer.de.com\/index.php\/2023\/12\/07\/hello-world\/?lang=en","title":{"rendered":"Hello world!"},"content":{"rendered":"\n<p>Welcome to WordPress. This is your first post. Edit or delete it and start writing!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Welcome to WordPress. This is your first post. Edit or delete it and start writing!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-242376","post","type-post","status-publish","format-standard","hentry","category-nicht-kategorisiert"],"_links":{"self":[{"href":"https:\/\/schaeffner-neu.freischwimmer.de.com\/index.php\/wp-json\/wp\/v2\/posts\/242376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schaeffner-neu.freischwimmer.de.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schaeffner-neu.freischwimmer.de.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schaeffner-neu.freischwimmer.de.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/schaeffner-neu.freischwimmer.de.com\/index.php\/wp-json\/wp\/v2\/comments?post=242376"}],"version-history":[{"count":2,"href":"https:\/\/schaeffner-neu.freischwimmer.de.com\/index.php\/wp-json\/wp\/v2\/posts\/242376\/revisions"}],"predecessor-version":[{"id":242378,"href":"https:\/\/schaeffner-neu.freischwimmer.de.com\/index.php\/wp-json\/wp\/v2\/posts\/242376\/revisions\/242378"}],"wp:attachment":[{"href":"https:\/\/schaeffner-neu.freischwimmer.de.com\/index.php\/wp-json\/wp\/v2\/media?parent=242376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schaeffner-neu.freischwimmer.de.com\/index.php\/wp-json\/wp\/v2\/categories?post=242376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schaeffner-neu.freischwimmer.de.com\/index.php\/wp-json\/wp\/v2\/tags?post=242376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}